{"id":1581,"date":"2024-12-26T09:56:49","date_gmt":"2024-12-26T09:56:49","guid":{"rendered":"https:\/\/dr-nimriclinic.com\/?page_id=1581"},"modified":"2026-05-18T08:47:54","modified_gmt":"2026-05-18T08:47:54","slug":"orthodontic-treatments","status":"publish","type":"page","link":"https:\/\/dr-nimriclinic.com\/ar\/services\/orthodontic-treatments\/","title":{"rendered":"\u0639\u0644\u0627\u062c\u0627\u062a \u062a\u0642\u0648\u064a\u0645 \u0627\u0644\u0623\u0633\u0646\u0627\u0646"},"content":{"rendered":"<p><section id=\"bt_bb_section6a57f99f9a553\" class=\"bt_bb_section bt_bb_color_scheme_1 bt_bb_layout_boxed_1200 bt_bb_vertical_align_top bt_bb_background_overlay_alternate_solid bt_bb_section_show_left_boxed_content\" style=\"; --section-primary-color:#ffffff; --section-secondary-color:#191919;;background-color:rgb(147,87,34);\" data-bt-override-class=\"null\"><div class=\"bt_bb_background_image_holder_wrapper\"><div class=\"bt_bb_background_image_holder btLazyLoadBackground\"  data-background_image_src=\"https:\/\/dr-nimriclinic.com\/wp-content\/uploads\/2020\/01\/background-4.jpg\" data-parallax-zoom-start=\"1\" data-parallax-zoom-end=\"1\" data-parallax-blur-start=\"0\" data-parallax-blur-end=\"0\" data-parallax-opacity-start=\"1\" data-parallax-opacity-end=\"1\" style=\" background-image: url(&#039;https:\/\/dr-nimriclinic.com\/wp-content\/plugins\/bold-page-builder\/img\/blank.gif&#039;);\"><\/div><\/div><div class=\"bt_bb_port\"><div class=\"bt_bb_cell\"><div class=\"bt_bb_cell_inner\"><div class=\"bt_bb_row  bt_bb_column_gap_25\" style=\"; --column-gap:25px;\" data-bt-override-class=\"{}\"><div class=\"bt_bb_row_holder\" ><div  class=\"bt_bb_column col-xxl-6 col-xl-6 bt_bb_vertical_align_middle bt_bb_align_left bt_bb_padding_double bt_bb_animation_fade_in animate\"  data-width=\"6\" data-bt-override-class=\"{}\"><div class=\"bt_bb_column_content\"><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_top_spacing_small bt_bb_bottom_spacing_normal\" data-bt-override-class=\"null\"><\/div><header class=\"bt_bb_headline bt_bb_font_weight_600 bt_bb_text_transform_capitalize bt_bb_dash_none bt_bb_size_extrahuge bt_bb_align_inherit bt_bb_dash_type_none\" data-bt-override-class=\"{&quot;bt_bb_size_&quot;:{&quot;current_class&quot;:&quot;bt_bb_size_extrahuge&quot;,&quot;def&quot;:&quot;extrahuge&quot;}}\"><h1 class=\"bt_bb_headline_tag\"><span class=\"bt_bb_headline_content\"><span><small>\u0639\u0644\u0627\u062c\u0627\u062a \u062a\u0642\u0648\u064a\u0645 \u0627\u0644\u0623\u0633\u0646\u0627\u0646<\/small><\/span><\/span><\/h1><\/header><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_bottom_spacing_small\" data-bt-override-class=\"null\"><\/div><div  class=\"bt_bb_text bt_bb_animation_fade_in animate\" style=\"padding: 0;\"><\/p>\n<p><strong>\u0627\u0644\u062d\u0635\u0648\u0644 \u0639\u0644\u0649 \u0627\u0628\u062a\u0633\u0627\u0645\u0629 \u062c\u0645\u064a\u0644\u0629 \u0648\u0635\u062d\u064a\u0629<\/strong><\/p>\n<p>\u062a\u064f\u0635\u0645\u0651\u064e\u0645 \u0639\u0644\u0627\u062c\u0627\u062a \u062a\u0642\u0648\u064a\u0645 \u0627\u0644\u0623\u0633\u0646\u0627\u0646 \u0644\u062a\u0635\u062d\u064a\u062d \u0639\u062f\u0645 \u0627\u0646\u062a\u0638\u0627\u0645 \u0627\u0644\u0623\u0633\u0646\u0627\u0646 \u0648\u0627\u0644\u0641\u0643\u064a\u0646\u060c \u0645\u0645\u0627 \u064a\u062d\u0633\u0651\u0646 \u0645\u0646 \u0648\u0638\u064a\u0641\u0629 \u0627\u0644\u0623\u0633\u0646\u0627\u0646 \u0648\u0645\u0638\u0647\u0631 \u0627\u0644\u0627\u0628\u062a\u0633\u0627\u0645\u0629 \u0641\u064a \u0622\u0646\u064d \u0648\u0627\u062d\u062f.<\/p>\n<p>\n<\/div><div class=\"bt_bb_separator bt_bb_border_style_dotted bt_bb_top_spacing_extra_small bt_bb_bottom_spacing_small\" data-bt-override-class=\"{&quot;bt_bb_top_spacing_&quot;:{&quot;current_class&quot;:&quot;bt_bb_top_spacing_extra_small&quot;,&quot;def&quot;:&quot;extra_small&quot;},&quot;bt_bb_bottom_spacing_&quot;:{&quot;current_class&quot;:&quot;bt_bb_bottom_spacing_small&quot;,&quot;def&quot;:&quot;small&quot;}}\"><\/div><div  class=\"bt_bb_text\" ><\/p>\n<div class=\"flex-1 overflow-hidden @container\/thread\">\n<div class=\"h-full\">\n<div class=\"react-scroll-to-bottom--css-stfqo-79elbk h-full\">\n<div class=\"react-scroll-to-bottom--css-stfqo-1n7m0yu\">\n<div class=\"flex flex-col text-sm md:pb-9\">\n<article class=\"w-full scroll-mb-&#091;var(--thread-trailing-height,150px)&#093; text-token-text-primary focus-visible:outline-2 focus-visible:outline-offset-&#091;-4px&#093;\" dir=\"auto\" data-testid=\"conversation-turn-49\" data-scroll-anchor=\"true\">\n<div class=\"m-auto text-base py-&#091;18px&#093; px-3 md:px-4 w-full md:px-5 lg:px-4 xl:px-5\">\n<div class=\"mx-auto flex flex-1 gap-4 text-base md:gap-5 lg:gap-6 md:max-w-3xl\">\n<div class=\"group\/conversation-turn relative flex w-full min-w-0 flex-col agent-turn\">\n<div class=\"flex-col gap-1 md:gap-3\">\n<div class=\"flex max-w-full flex-col flex-grow\">\n<div class=\"min-h-8 text-message flex w-full flex-col items-end gap-2 whitespace-normal break-words text-start &#091;.text-message+&#038;&#093;:mt-5\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-&#091;3px&#093;\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n<p class=\"translation-block\"><strong>\u062a\u0642\u0648\u064a\u0645 \u0627\u0644\u0623\u0633\u0646\u0627\u0646<\/strong> \u0647\u0648 \u0641\u0631\u0639 \u0645\u0646 \u0637\u0628 \u0627\u0644\u0623\u0633\u0646\u0627\u0646 \u064a\u0633\u062a\u062e\u062f\u0645 \u0627\u0644\u062a\u0642\u0648\u064a\u0645 \u0627\u0644\u062b\u0627\u0628\u062a \u0648\u0627\u0644\u0645\u062a\u062d\u0631\u0643 \u0648\u0627\u0644\u0623\u062c\u0647\u0632\u0629 \u0627\u0644\u062a\u0642\u0648\u064a\u0645\u064a\u0629 \u0627\u0644\u0623\u062e\u0631\u0649 \u0644\u062a\u0642\u0648\u064a\u0645 \u0627\u0644\u0623\u0633\u0646\u0627\u0646\u060c \u0648\u062a\u0635\u062d\u064a\u062d \u0645\u0634\u0643\u0644\u0627\u062a \u0627\u0644\u0625\u0637\u0628\u0627\u0642\u060c \u0648\u062a\u062d\u0642\u064a\u0642 \u0627\u0628\u062a\u0633\u0627\u0645\u0629 \u0645\u062a\u0646\u0627\u0633\u0642\u0629 \u0648\u0645\u062a\u0648\u0627\u0632\u0646\u0629. \u0633\u0648\u0627\u0621 \u0643\u0627\u0646 \u0627\u0644\u0647\u062f\u0641 \u0639\u0644\u0627\u062c \u062a\u0632\u0627\u062d\u0645 \u0627\u0644\u0623\u0633\u0646\u0627\u0646\u060c \u0623\u0648 \u0627\u0644\u0641\u062c\u0648\u0627\u062a\u060c \u0623\u0648 \u0627\u0644\u0639\u0636\u0629 \u0627\u0644\u0639\u0644\u0648\u064a\u0629 \u0623\u0648 \u0627\u0644\u0633\u0641\u0644\u064a\u0629 \u0623\u0648 \u0627\u0644\u0645\u0639\u0643\u0648\u0633\u0629\u060c \u0641\u0625\u0646 \u0639\u0644\u0627\u062c \u0627\u0644\u062a\u0642\u0648\u064a\u0645 \u0644\u0627 \u064a\u062d\u0633\u0646 \u0627\u0644\u0645\u0638\u0647\u0631 \u0627\u0644\u062c\u0645\u0627\u0644\u064a \u0641\u062d\u0633\u0628\u060c \u0628\u0644 \u064a\u0639\u0632\u0632 \u0623\u064a\u0636\u064b\u0627 \u0635\u062d\u0629 \u0627\u0644\u0641\u0645 \u0628\u0634\u0643\u0644 \u0639\u0627\u0645. \u0625\u0646 \u0627\u0644\u0625\u0637\u0628\u0627\u0642 \u0627\u0644\u0635\u062d\u064a\u062d \u064a\u0633\u0627\u0639\u062f \u0639\u0644\u0649 \u062a\u0642\u0644\u064a\u0644 \u062e\u0637\u0631 \u062a\u0633\u0648\u0633 \u0627\u0644\u0623\u0633\u0646\u0627\u0646\u060c \u0648\u0623\u0645\u0631\u0627\u0636 \u0627\u0644\u0644\u062b\u0629\u060c \u0648\u062d\u062a\u0649 \u0622\u0644\u0627\u0645 \u0627\u0644\u0641\u0643 \u0627\u0644\u0646\u0627\u062a\u062c\u0629 \u0639\u0646 \u0633\u0648\u0621 \u0627\u0644\u0645\u062d\u0627\u0630\u0627\u0629. \u0648\u0645\u0639 \u0627\u0644\u062a\u0637\u0648\u0631 \u0627\u0644\u062a\u0643\u0646\u0648\u0644\u0648\u062c\u064a\u060c \u0623\u0635\u0628\u062d\u062a \u0639\u0644\u0627\u062c\u0627\u062a \u0627\u0644\u062a\u0642\u0648\u064a\u0645 \u0627\u0644\u064a\u0648\u0645 \u0623\u0643\u062b\u0631 \u0631\u0627\u062d\u0629 \u0648\u0641\u0639\u0627\u0644\u064a\u0629 \u0648\u062e\u0635\u0648\u0635\u064a\u0629 \u0645\u0646 \u0623\u064a \u0648\u0642\u062a \u0645\u0636\u0649.<\/p>\n<\/div>\n<p>\u00a0<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>\n<\/div><\/div><\/div><div  class=\"bt_bb_column col-xxl-6 col-xl-6 bt_bb_vertical_align_middle bt_bb_align_left btLazyLoadBackground bt_bb_column_background_image bt_bb_mobile_align_to_both_edges bt_bb_padding_normal bt_bb_animation_fade_in animate\" style=\"padding: 0;background-image:url(&#039;https:\/\/dr-nimriclinic.com\/wp-content\/plugins\/bold-page-builder\/img\/blank.gif&#039;);\" data-background_image_src='https:\/\/dr-nimriclinic.com\/wp-content\/uploads\/2024\/12\/Orthodontics-Who-Can-Benefit-from-Orthodontic-Treatment.webp' data-width=\"6\" data-bt-override-class=\"{}\"><div class=\"bt_bb_column_content\"><\/div><\/div><\/div><\/div><\/div><!-- cell_inner --><\/div><!-- cell --><\/div><!-- port --><\/section><section id=\"bt_bb_section6a57f99f9b23a\" class=\"bt_bb_section bt_bb_layout_boxed_1200 bt_bb_vertical_align_top\" style=\"z-index: 2;background-size:100% auto;\" data-bt-override-class=\"null\"><div class=\"bt_bb_background_image_holder_wrapper\"><div class=\"bt_bb_background_image_holder btLazyLoadBackground bt_bb_parallax\"  data-background_image_src=\"https:\/\/dr-nimriclinic.com\/wp-content\/uploads\/2020\/02\/background-3.png\" data-parallax=\"0.7\" data-parallax-offset=\"400\" data-parallax-zoom-start=\"1\" data-parallax-zoom-end=\"1\" data-parallax-blur-start=\"0\" data-parallax-blur-end=\"0\" data-parallax-opacity-start=\"1\" data-parallax-opacity-end=\"1\" style=\" background-image: url(&#039;https:\/\/dr-nimriclinic.com\/wp-content\/plugins\/bold-page-builder\/img\/blank.gif&#039;);\"><\/div><\/div><div class=\"bt_bb_port\"><div class=\"bt_bb_cell\"><div class=\"bt_bb_cell_inner\"><div class=\"bt_bb_row  bt_bb_column_gap_25\" style=\"; --column-gap:25px;\" data-bt-override-class=\"{}\"><div class=\"bt_bb_row_holder\" style=\"margin-top: -3em;\"><div  class=\"bt_bb_column col-xxl-8 col-xl-8 bt_bb_vertical_align_top bt_bb_align_left bt_bb_padding_normal bt_bb_animation_fade_in animate\"  data-width=\"8\" data-bt-override-class=\"{}\"><div class=\"bt_bb_column_content\"><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_top_spacing_normal bt_bb_bottom_spacing_large\" data-bt-override-class=\"null\"><\/div><header class=\"bt_bb_headline bt_bb_font_weight_bolder bt_bb_color_scheme_17 bt_bb_dash_none bt_bb_size_extralarge bt_bb_align_inherit bt_bb_dash_type_none\" style=\"; --primary-color:#6b5546; --secondary-color:#564c38;\" data-bt-override-class=\"{}\"><h2 class=\"bt_bb_headline_tag translation-block\"><span class=\"bt_bb_headline_content\"><span><small>\u0645\u0627 \u0647\u064a<\/small><br>\u0639\u0644\u0627\u062c\u0627\u062a \u062a\u0642\u0648\u064a\u0645 \u0627\u0644\u0623\u0633\u0646\u0627\u0646\u061f<\/span><\/span><\/h2><\/header><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_bottom_spacing_small\" data-bt-override-class=\"null\"><\/div><div  class=\"bt_bb_text\" ><\/p>\n<div class=\"flex-1 overflow-hidden @container\/thread\">\n<div class=\"h-full\">\n<div class=\"react-scroll-to-bottom--css-stfqo-79elbk h-full\">\n<div class=\"react-scroll-to-bottom--css-stfqo-1n7m0yu\">\n<div class=\"flex flex-col text-sm md:pb-9\">\n<article class=\"w-full scroll-mb-&#091;var(--thread-trailing-height,150px)&#093; text-token-text-primary focus-visible:outline-2 focus-visible:outline-offset-&#091;-4px&#093;\" dir=\"auto\" data-testid=\"conversation-turn-49\" data-scroll-anchor=\"true\">\n<div class=\"m-auto text-base py-&#091;18px&#093; px-3 md:px-4 w-full md:px-5 lg:px-4 xl:px-5\">\n<div class=\"mx-auto flex flex-1 gap-4 text-base md:gap-5 lg:gap-6 md:max-w-3xl\">\n<div class=\"group\/conversation-turn relative flex w-full min-w-0 flex-col agent-turn\">\n<div class=\"flex-col gap-1 md:gap-3\">\n<div class=\"flex max-w-full flex-col flex-grow\">\n<div class=\"min-h-8 text-message flex w-full flex-col items-end gap-2 whitespace-normal break-words text-start &#091;.text-message+&#038;&#093;:mt-5\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-&#091;3px&#093;\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n<p class=\"translation-block\"><strong>\u062a\u0642\u0648\u064a\u0645 \u0627\u0644\u0623\u0633\u0646\u0627\u0646<\/strong> \u0647\u0648 \u0641\u0631\u0639 \u0645\u0646 \u0637\u0628 \u0627\u0644\u0623\u0633\u0646\u0627\u0646 \u064a\u0633\u062a\u062e\u062f\u0645 \u0627\u0644\u062a\u0642\u0648\u064a\u0645 \u0627\u0644\u062b\u0627\u0628\u062a \u0648\u0627\u0644\u0645\u062a\u062d\u0631\u0643 \u0648\u0627\u0644\u0623\u062c\u0647\u0632\u0629 \u0627\u0644\u062a\u0642\u0648\u064a\u0645\u064a\u0629 \u0627\u0644\u0623\u062e\u0631\u0649 \u0644\u062a\u0642\u0648\u064a\u0645 \u0627\u0644\u0623\u0633\u0646\u0627\u0646\u060c \u0648\u062a\u0635\u062d\u064a\u062d \u0645\u0634\u0643\u0644\u0627\u062a \u0627\u0644\u0625\u0637\u0628\u0627\u0642\u060c \u0648\u062a\u062d\u0642\u064a\u0642 \u0627\u0628\u062a\u0633\u0627\u0645\u0629 \u0645\u062a\u0646\u0627\u0633\u0642\u0629 \u0648\u0645\u062a\u0648\u0627\u0632\u0646\u0629. \u0633\u0648\u0627\u0621 \u0643\u0627\u0646 \u0627\u0644\u0647\u062f\u0641 \u0639\u0644\u0627\u062c \u062a\u0632\u0627\u062d\u0645 \u0627\u0644\u0623\u0633\u0646\u0627\u0646\u060c \u0623\u0648 \u0627\u0644\u0641\u062c\u0648\u0627\u062a\u060c \u0623\u0648 \u0627\u0644\u0639\u0636\u0629 \u0627\u0644\u0639\u0644\u0648\u064a\u0629 \u0623\u0648 \u0627\u0644\u0633\u0641\u0644\u064a\u0629 \u0623\u0648 \u0627\u0644\u0645\u0639\u0643\u0648\u0633\u0629\u060c \u0641\u0625\u0646 \u0639\u0644\u0627\u062c \u0627\u0644\u062a\u0642\u0648\u064a\u0645 \u0644\u0627 \u064a\u062d\u0633\u0646 \u0627\u0644\u0645\u0638\u0647\u0631 \u0627\u0644\u062c\u0645\u0627\u0644\u064a \u0641\u062d\u0633\u0628\u060c \u0628\u0644 \u064a\u0639\u0632\u0632 \u0623\u064a\u0636\u064b\u0627 \u0635\u062d\u0629 \u0627\u0644\u0641\u0645 \u0628\u0634\u0643\u0644 \u0639\u0627\u0645. \u0625\u0646 \u0627\u0644\u0625\u0637\u0628\u0627\u0642 \u0627\u0644\u0635\u062d\u064a\u062d \u064a\u0633\u0627\u0639\u062f \u0639\u0644\u0649 \u062a\u0642\u0644\u064a\u0644 \u062e\u0637\u0631 \u062a\u0633\u0648\u0633 \u0627\u0644\u0623\u0633\u0646\u0627\u0646\u060c \u0648\u0623\u0645\u0631\u0627\u0636 \u0627\u0644\u0644\u062b\u0629\u060c \u0648\u062d\u062a\u0649 \u0622\u0644\u0627\u0645 \u0627\u0644\u0641\u0643 \u0627\u0644\u0646\u0627\u062a\u062c\u0629 \u0639\u0646 \u0633\u0648\u0621 \u0627\u0644\u0645\u062d\u0627\u0630\u0627\u0629. \u0648\u0645\u0639 \u0627\u0644\u062a\u0637\u0648\u0631 \u0627\u0644\u062a\u0643\u0646\u0648\u0644\u0648\u062c\u064a\u060c \u0623\u0635\u0628\u062d\u062a \u0639\u0644\u0627\u062c\u0627\u062a \u0627\u0644\u062a\u0642\u0648\u064a\u0645 \u0627\u0644\u064a\u0648\u0645 \u0623\u0643\u062b\u0631 \u0631\u0627\u062d\u0629 \u0648\u0641\u0639\u0627\u0644\u064a\u0629 \u0648\u062e\u0635\u0648\u0635\u064a\u0629 \u0645\u0646 \u0623\u064a \u0648\u0642\u062a \u0645\u0636\u0649.<\/p>\n<\/div>\n<h3>\u0623\u0647\u0645 \u0645\u0645\u064a\u0632\u0627\u062a \u0639\u0644\u0627\u062c\u0627\u062a \u062a\u0642\u0648\u064a\u0645 \u0627\u0644\u0623\u0633\u0646\u0627\u0646:<\/h3>\n<ol>\n<li class=\"translation-block\"><strong>\u0627\u0644\u0623\u0642\u0648\u0627\u0633 \u0648\u0627\u0644\u062a\u0642\u0648\u064a\u0645 \u0627\u0644\u0634\u0641\u0627\u0641<\/strong>: \u062a\u062a\u0643\u0648\u0646 \u0627\u0644\u0623\u0642\u0648\u0627\u0633 \u0627\u0644\u062a\u0642\u0644\u064a\u062f\u064a\u0629 \u0645\u0646 \u062d\u0627\u0635\u0631\u0627\u062a \u0645\u0639\u062f\u0646\u064a\u0629 \u0648\u0623\u0633\u0644\u0627\u0643\u060c \u0628\u064a\u0646\u0645\u0627 \u062a\u064f\u0639\u062f\u0651 \u0627\u0644\u062a\u0642\u0648\u064a\u0645\u0627\u062a \u0627\u0644\u0634\u0641\u0627\u0641\u0629 (\u0645\u062b\u0644 Invisalign) \u062e\u064a\u0627\u0631\u064b\u0627 \u0623\u0643\u062b\u0631 \u0633\u0631\u064a\u0629. \u064a\u0639\u0645\u0644 \u0643\u0644\u0627 \u0627\u0644\u0646\u0648\u0639\u064a\u0646 \u0639\u0644\u0649 \u062a\u062d\u0631\u064a\u0643 \u0627\u0644\u0623\u0633\u0646\u0627\u0646 \u062a\u062f\u0631\u064a\u062c\u064a\u064b\u0627 \u0625\u0644\u0649 \u0648\u0636\u0639 \u0623\u0641\u0636\u0644 \u0648\u0645\u062d\u0627\u0630\u0627\u0629 \u0635\u062d\u064a\u062d\u0629 \u0645\u0639 \u0645\u0631\u0648\u0631 \u0627\u0644\u0648\u0642\u062a.<\/li>\n<li class=\"translation-block\"><strong>\u062e\u0637\u0637 \u0639\u0644\u0627\u062c \u0645\u062e\u0635\u0635\u0629<\/strong>: \u064a\u062a\u0645 \u062a\u0635\u0645\u064a\u0645 \u062e\u0637\u0637 \u0639\u0644\u0627\u062c \u062a\u0642\u0648\u064a\u0645 \u0627\u0644\u0623\u0633\u0646\u0627\u0646 \u0628\u0634\u0643\u0644 \u0641\u0631\u062f\u064a \u0644\u062a\u0644\u0628\u064a\u0629 \u0627\u062d\u062a\u064a\u0627\u062c\u0627\u062a \u0643\u0644 \u0645\u0631\u064a\u0636\u060c \u0628\u0645\u0627 \u0641\u064a \u0630\u0644\u0643 \u0634\u062f\u0629 \u0639\u062f\u0645 \u0627\u0646\u062a\u0638\u0627\u0645 \u0627\u0644\u0623\u0633\u0646\u0627\u0646 \u0648\u0627\u0644\u0646\u062a\u0627\u0626\u062c \u0627\u0644\u0645\u0631\u062c\u0648\u0629.<\/li>\n<li class=\"translation-block\"><strong>\u062a\u062d\u0633\u064a\u0646 \u0635\u062d\u0629 \u0627\u0644\u0623\u0633\u0646\u0627\u0646<\/strong>: \u0625\u0646 \u062a\u0642\u0648\u064a\u0645 \u0627\u0644\u0623\u0633\u0646\u0627\u0646 \u0644\u0627 \u064a\u062d\u0633\u0651\u0646 \u0627\u0644\u0645\u0638\u0647\u0631 \u0641\u0642\u0637\u060c \u0628\u0644 \u064a\u0639\u0632\u0632 \u0623\u064a\u0636\u064b\u0627 \u0635\u062d\u0629 \u0627\u0644\u0641\u0645 \u0645\u0646 \u062e\u0644\u0627\u0644 \u062a\u0633\u0647\u064a\u0644 \u062a\u0646\u0638\u064a\u0641 \u0627\u0644\u0623\u0633\u0646\u0627\u0646 \u0648\u062a\u0642\u0644\u064a\u0644 \u062e\u0637\u0631 \u0627\u0644\u062a\u0633\u0648\u0633 \u0648\u0623\u0645\u0631\u0627\u0636 \u0627\u0644\u0644\u062b\u0629.<\/li>\n<li class=\"translation-block\"><strong>\u0646\u062a\u0627\u0626\u062c \u0637\u0648\u064a\u0644\u0629 \u0627\u0644\u0623\u0645\u062f<\/strong>: \u062a\u0645 \u062a\u0635\u0645\u064a\u0645 \u0639\u0644\u0627\u062c\u0627\u062a \u062a\u0642\u0648\u064a\u0645 \u0627\u0644\u0623\u0633\u0646\u0627\u0646 \u0644\u062a\u0642\u062f\u064a\u0645 \u0646\u062a\u0627\u0626\u062c \u062f\u0627\u0626\u0645\u0629\u060c \u0645\u0645\u0627 \u064a\u0636\u0645\u0646 \u0628\u0642\u0627\u0621 \u0627\u0644\u0623\u0633\u0646\u0627\u0646 \u0641\u064a \u0648\u0636\u0639\u0647\u0627 \u0627\u0644\u0635\u062d\u064a\u062d \u0648\u0627\u0633\u062a\u0645\u0631\u0627\u0631 \u0627\u0644\u0625\u0637\u0628\u0627\u0642 \u0627\u0644\u0633\u0644\u064a\u0645 \u0644\u0641\u062a\u0631\u0629 \u0637\u0648\u064a\u0644\u0629 \u0628\u0639\u062f \u0627\u0646\u062a\u0647\u0627\u0621 \u0627\u0644\u0639\u0644\u0627\u062c.<\/li>\n<\/ol>\n<h3>\u0641\u0648\u0627\u0626\u062f \u0639\u0644\u0627\u062c\u0627\u062a \u062a\u0642\u0648\u064a\u0645 \u0627\u0644\u0623\u0633\u0646\u0627\u0646:<\/h3>\n<ul>\n<li>\n<p class=\"translation-block\"><strong>\u062a\u062d\u0633\u064a\u0646 \u0627\u0644\u0645\u0638\u0647\u0631 \u0627\u0644\u062c\u0645\u0627\u0644\u064a<\/strong>: \u0645\u0646 \u0623\u0628\u0631\u0632 \u0641\u0648\u0627\u0626\u062f \u062a\u0642\u0648\u064a\u0645 \u0627\u0644\u0623\u0633\u0646\u0627\u0646 \u0627\u0644\u062d\u0635\u0648\u0644 \u0639\u0644\u0649 \u0627\u0628\u062a\u0633\u0627\u0645\u0629 \u0623\u0643\u062b\u0631 \u062c\u0627\u0630\u0628\u064a\u0629. \u0641\u062a\u0635\u062d\u064a\u062d \u0627\u0644\u0623\u0633\u0646\u0627\u0646 \u063a\u064a\u0631 \u0627\u0644\u0645\u0646\u062a\u0638\u0645\u0629 \u064a\u0645\u0643\u0646 \u0623\u0646 \u064a\u062d\u0633\u0651\u0646 \u0628\u0634\u0643\u0644 \u0643\u0628\u064a\u0631 \u0645\u0638\u0647\u0631 \u0627\u0644\u0648\u062c\u0647 \u0648\u064a\u0639\u0632\u0632 \u0627\u0644\u062b\u0642\u0629 \u0628\u0627\u0644\u0646\u0641\u0633.<\/p>\n<\/li>\n<li>\n<p class=\"translation-block\"><strong>\u062a\u062d\u0633\u064a\u0646 \u0648\u0638\u064a\u0641\u0629 \u0627\u0644\u0625\u0637\u0628\u0627\u0642<\/strong>: \u064a\u0639\u0645\u0644 \u062a\u0642\u0648\u064a\u0645 \u0627\u0644\u0623\u0633\u0646\u0627\u0646 \u0639\u0644\u0649 \u062a\u0635\u062d\u064a\u062d \u0645\u0634\u0643\u0644\u0627\u062a \u0627\u0644\u0625\u0637\u0628\u0627\u0642 \u0645\u062b\u0644 \u0627\u0644\u0639\u0636\u0629 \u0627\u0644\u0639\u0644\u0648\u064a\u0629 \u0623\u0648 \u0627\u0644\u0633\u0641\u0644\u064a\u0629 \u0623\u0648 \u0627\u0644\u0645\u0639\u0643\u0648\u0633\u0629\u060c \u0645\u0645\u0627 \u064a\u0633\u0627\u0639\u062f \u0639\u0644\u0649 \u062a\u0644\u0627\u0645\u0633 \u0627\u0644\u0623\u0633\u0646\u0627\u0646 \u0628\u0634\u0643\u0644 \u0635\u062d\u064a\u062d \u0623\u062b\u0646\u0627\u0621 \u0627\u0644\u0645\u0636\u063a \u0648\u0627\u0644\u062a\u062d\u062f\u062b \u0648\u0627\u0644\u0627\u0628\u062a\u0633\u0627\u0645.<\/p>\n<\/li>\n<li>\n<p class=\"translation-block\"><strong>\u062a\u062d\u0633\u064a\u0646 \u0635\u062d\u0629 \u0627\u0644\u0641\u0645<\/strong>: \u0627\u0644\u0623\u0633\u0646\u0627\u0646 \u0627\u0644\u0645\u0633\u062a\u0642\u064a\u0645\u0629 \u0623\u0633\u0647\u0644 \u0641\u064a \u0627\u0644\u062a\u0646\u0638\u064a\u0641\u060c \u0645\u0645\u0627 \u064a\u0642\u0644\u0644 \u0645\u0646 \u062e\u0637\u0631 \u0627\u0644\u062a\u0633\u0648\u0633 \u0648\u0623\u0645\u0631\u0627\u0636 \u0627\u0644\u0644\u062b\u0629 \u0648\u062a\u0622\u0643\u0644 \u0627\u0644\u0623\u0633\u0646\u0627\u0646. \u0643\u0645\u0627 \u0623\u0646 \u0627\u0644\u0645\u062d\u0627\u0630\u0627\u0629 \u0627\u0644\u0635\u062d\u064a\u062d\u0629 \u062a\u0633\u0627\u0639\u062f \u0641\u064a \u0627\u0644\u0648\u0642\u0627\u064a\u0629 \u0645\u0646 \u0645\u0634\u0627\u0643\u0644 \u0627\u0644\u0641\u0643\u060c \u0645\u062b\u0644 \u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0645\u0641\u0635\u0644 \u0627\u0644\u0641\u0643\u064a \u0627\u0644\u0635\u062f\u063a\u064a (TMJ)\u060c \u0627\u0644\u0646\u0627\u062a\u062c\u0629 \u0639\u0646 \u0639\u062f\u0645 \u0627\u0646\u062a\u0638\u0627\u0645 \u0627\u0644\u0623\u0633\u0646\u0627\u0646.<\/p>\n<\/li>\n<li>\n<p class=\"translation-block\"><strong>\u0627\u0633\u062a\u062b\u0645\u0627\u0631 \u0637\u0648\u064a\u0644 \u0627\u0644\u0623\u0645\u062f<\/strong>: \u064a\u0648\u0641\u0631 \u062a\u0642\u0648\u064a\u0645 \u0627\u0644\u0623\u0633\u0646\u0627\u0646 \u062d\u0644\u0627\u064b \u062f\u0627\u0626\u0645\u064b\u0627\u060c \u062d\u064a\u062b \u062a\u0645\u062a\u062f \u0646\u062a\u0627\u0626\u062c\u0647 \u0644\u062a\u0634\u0645\u0644 \u062a\u062d\u0633\u064a\u0646 \u0648\u0638\u064a\u0641\u0629 \u0627\u0644\u0623\u0633\u0646\u0627\u0646 \u0648\u0645\u0638\u0647\u0631\u0647\u0627 \u0627\u0644\u062c\u0645\u0627\u0644\u064a \u0644\u0633\u0646\u0648\u0627\u062a \u0637\u0648\u064a\u0644\u0629. \u0643\u0645\u0627 \u064a\u0633\u0627\u0647\u0645 \u0641\u064a \u062a\u062d\u0633\u064a\u0646 \u062c\u0648\u062f\u0629 \u0627\u0644\u062d\u064a\u0627\u0629 \u0628\u0634\u0643\u0644 \u0639\u0627\u0645 \u0645\u0646 \u062e\u0644\u0627\u0644 \u062a\u0639\u0632\u064a\u0632 \u0635\u062d\u0629 \u0627\u0644\u0641\u0645 \u0648\u0645\u0646\u062d \u0627\u0628\u062a\u0633\u0627\u0645\u0629 \u0623\u0643\u062b\u0631 \u062b\u0642\u0629.<\/p>\n<\/li>\n<li>\n<p class=\"translation-block\"><strong>\u0627\u0644\u0631\u0627\u062d\u0629 \u0648\u0627\u0644\u0633\u0647\u0648\u0644\u0629<\/strong>: \u0645\u0639 \u0627\u0644\u062a\u0637\u0648\u0631 \u0627\u0644\u062d\u062f\u064a\u062b \u0641\u064a \u0645\u062c\u0627\u0644 \u062a\u0642\u0648\u064a\u0645 \u0627\u0644\u0623\u0633\u0646\u0627\u0646\u060c \u0623\u0635\u0628\u062d\u062a \u0627\u0644\u0639\u0644\u0627\u062c\u0627\u062a \u0623\u0643\u062b\u0631 \u0631\u0627\u062d\u0629 \u0645\u0646 \u0623\u064a \u0648\u0642\u062a \u0645\u0636\u0649. \u0639\u0644\u0649 \u0633\u0628\u064a\u0644 \u0627\u0644\u0645\u062b\u0627\u0644\u060c \u064a\u0645\u0643\u0646 \u0625\u0632\u0627\u0644\u0629 \u0627\u0644\u062a\u0642\u0648\u064a\u0645 \u0627\u0644\u0634\u0641\u0627\u0641 \u0628\u0633\u0647\u0648\u0644\u0629\u060c \u0645\u0645\u0627 \u064a\u0633\u0645\u062d \u0644\u0644\u0645\u0631\u0636\u0649 \u0628\u0627\u0644\u0623\u0643\u0644 \u0648\u0627\u0644\u0634\u0631\u0628 \u0648\u062a\u0646\u0638\u064a\u0641 \u0627\u0644\u0623\u0633\u0646\u0627\u0646 \u062f\u0648\u0646 \u0623\u064a \u0642\u064a\u0648\u062f.<\/p>\n<\/li>\n<\/ul>\n<p>\u00a0<\/p>\n<p>\u0628\u0627\u062e\u062a\u0635\u0627\u0631\u060c \u062a\u0648\u0641\u0631 \u0639\u0644\u0627\u062c\u0627\u062a \u062a\u0642\u0648\u064a\u0645 \u0627\u0644\u0623\u0633\u0646\u0627\u0646 \u062d\u0644\u0627\u064b \u0634\u0627\u0645\u0644\u0627\u064b \u0644\u062a\u0635\u062d\u064a\u062d \u0639\u062f\u0645 \u0627\u0646\u062a\u0638\u0627\u0645 \u0627\u0644\u0623\u0633\u0646\u0627\u0646 \u0648\u0627\u0644\u0641\u0643\u064a\u0646\u060c \u0645\u0645\u0627 \u064a\u062d\u0633\u0646 \u0648\u0638\u064a\u0641\u0629 \u0627\u0644\u0623\u0633\u0646\u0627\u0646 \u0648\u064a\u0639\u0632\u0632 \u0645\u0638\u0647\u0631 \u0627\u0644\u0627\u0628\u062a\u0633\u0627\u0645\u0629 \u0641\u064a \u0622\u0646\u064d \u0648\u0627\u062d\u062f. \u0633\u0648\u0627\u0621 \u0645\u0646 \u062e\u0644\u0627\u0644 \u0627\u0644\u0623\u0642\u0648\u0627\u0633 \u0627\u0644\u062a\u0642\u0644\u064a\u062f\u064a\u0629 \u0623\u0648 \u0627\u0644\u062a\u0642\u0648\u064a\u0645 \u0627\u0644\u0634\u0641\u0627\u0641 \u0627\u0644\u0623\u0643\u062b\u0631 \u0633\u0631\u064a\u0629\u060c \u064a\u0633\u0627\u0639\u062f \u062a\u0642\u0648\u064a\u0645 \u0627\u0644\u0623\u0633\u0646\u0627\u0646 \u0639\u0644\u0649 \u062a\u0639\u0632\u064a\u0632 \u0635\u062d\u0629 \u0627\u0644\u0641\u0645\u060c \u0648\u0632\u064a\u0627\u062f\u0629 \u0627\u0644\u062b\u0642\u0629 \u0628\u0627\u0644\u0646\u0641\u0633\u060c \u0648\u062a\u0642\u062f\u064a\u0645 \u0646\u062a\u0627\u0626\u062c \u0637\u0648\u064a\u0644\u0629 \u0627\u0644\u0623\u0645\u062f.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>\n<\/div><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_top_spacing_extra_small bt_bb_bottom_spacing_small\" data-bt-override-class=\"null\"><\/div><div class=\"bt_bb_masonry_image_grid bt_bb_grid_container bt_bb_columns_2 bt_bb_gap_normal\" style=\"margin-right: 20px;\" data-columns=\"2\"><div class=\"bt_bb_masonry_post_image_content\" data-columns=\"2\"><div class=\"bt_bb_grid_sizer\"><\/div><div class=\"bt_bb_grid_item bt_bb_tile_format11\" data-hw=\"0.6675\" data-src=\"https:\/\/dr-nimriclinic.com\/wp-content\/uploads\/2020\/02\/single-service-1-1280x854.jpg\" data-src-full=\"https:\/\/dr-nimriclinic.com\/wp-content\/uploads\/2020\/02\/single-service-1.jpg\" data-title=\"\"><div class=\"bt_bb_grid_item_inner\" data-hw=\"0.6675\" ><div class=\"bt_bb_grid_item_inner_image\"><\/div><div class=\"bt_bb_grid_item_inner_content\"><\/div><\/div><\/div><div class=\"bt_bb_grid_item bt_bb_tile_format11\" data-hw=\"0.6675\" data-src=\"https:\/\/dr-nimriclinic.com\/wp-content\/uploads\/2020\/02\/single-service-2-1280x854.jpg\" data-src-full=\"https:\/\/dr-nimriclinic.com\/wp-content\/uploads\/2020\/02\/single-service-2.jpg\" data-title=\"\"><div class=\"bt_bb_grid_item_inner\" data-hw=\"0.6675\" ><div class=\"bt_bb_grid_item_inner_image\"><\/div><div class=\"bt_bb_grid_item_inner_content\"><\/div><\/div><\/div><div class=\"bt_bb_grid_item bt_bb_tile_format11\" data-hw=\"0.6675\" data-src=\"https:\/\/dr-nimriclinic.com\/wp-content\/uploads\/2020\/02\/single-service-3-1280x854.jpg\" data-src-full=\"https:\/\/dr-nimriclinic.com\/wp-content\/uploads\/2020\/02\/single-service-3.jpg\" data-title=\"\"><div class=\"bt_bb_grid_item_inner\" data-hw=\"0.6675\" ><div class=\"bt_bb_grid_item_inner_image\"><\/div><div class=\"bt_bb_grid_item_inner_content\"><\/div><\/div><\/div><div class=\"bt_bb_grid_item bt_bb_tile_format11\" data-hw=\"0.6675\" data-src=\"https:\/\/dr-nimriclinic.com\/wp-content\/uploads\/2020\/02\/single-service-4-1280x854.jpg\" data-src-full=\"https:\/\/dr-nimriclinic.com\/wp-content\/uploads\/2020\/02\/single-service-4.jpg\" data-title=\"\"><div class=\"bt_bb_grid_item_inner\" data-hw=\"0.6675\" ><div class=\"bt_bb_grid_item_inner_image\"><\/div><div class=\"bt_bb_grid_item_inner_content\"><\/div><\/div><\/div><\/div><\/div><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_top_spacing_extra_small bt_bb_bottom_spacing_small\" data-bt-override-class=\"null\"><\/div><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_bottom_spacing_small\" data-bt-override-class=\"null\"><\/div><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_bottom_spacing_small\" data-bt-override-class=\"null\"><\/div><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_top_spacing_normal bt_bb_bottom_spacing_large bt_bb_hidden_md bt_bb_hidden_lg\" data-bt-override-class=\"null\"><\/div><\/div><\/div><div  class=\"bt_bb_column col-xxl-4 col-xl-4 bt_bb_vertical_align_top bt_bb_align_left bt_bb_padding_normal bt_bb_animation_fade_in animate\"  data-width=\"4\" data-bt-override-class=\"{}\"><div class=\"bt_bb_column_content\"><div class=\"bt_bb_row_inner\"   data-bt-override-class=\"{}\"><div class=\"bt_bb_row_inner_holder\"  ><div  class=\"bt_bb_column_inner col-xxl-12 col-xl-12 btDarkSkin bt_bb_align_left bt_bb_vertical_align_top bt_bb_padding_text_indent\" style=\"background-color:rgb(147,123,94);\" data-width=\"12\" data-bt-override-class=\"{}\"><div class=\"bt_bb_column_inner_content\"><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_bottom_spacing_normal\" data-bt-override-class=\"null\"><\/div><header class=\"bt_bb_headline bt_bb_dash_bottom bt_bb_size_normal bt_bb_align_inherit bt_bb_dash_type_none\" data-bt-override-class=\"{}\"><h4 class=\"bt_bb_headline_tag\"><span class=\"bt_bb_headline_content\"><span>\u0623\u0647\u0645 \u0627\u0644\u062e\u062f\u0645\u0627\u062a<\/span><\/span><\/h4><\/header><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_bottom_spacing_small\" data-bt-override-class=\"null\"><\/div><div class=\"bt_bb_custom_menu btMenuAsInSidebar bt_bb_direction_vertical\"><div class=\"menu-services-menu-container\"><ul id=\"menu-services-menu\" class=\"menu\"><li id=\"menu-item-942\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-942\"><a href=\"#\">\u0637\u0628 \u0627\u0644\u0623\u0633\u0646\u0627\u0646 \u0627\u0644\u0639\u0627\u0645<\/a><\/li>\n<li id=\"menu-item-943\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-943\"><a href=\"#\">\u0627\u0644\u0623\u0634\u0639\u0629 \u0627\u0644\u0633\u064a\u0646\u064a\u0629 (\u0627\u0644\u062a\u0635\u0648\u064a\u0631 \u0627\u0644\u0634\u0639\u0627\u0639\u064a)<\/a><\/li>\n<li id=\"menu-item-944\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-944\"><a href=\"#\">\u0637\u0628 \u0623\u0633\u0646\u0627\u0646 \u0627\u0644\u0623\u0637\u0641\u0627\u0644<\/a><\/li>\n<li id=\"menu-item-947\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-947\"><a href=\"https:\/\/dr-nimriclinic.com\/ar\/services\/root-canal-treatment\/\">\u062c\u0631\u0627\u062d\u0629 \u0627\u0644\u0623\u0633\u0646\u0627\u0646<\/a><\/li>\n<li id=\"menu-item-945\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-945\"><a href=\"#\">\u062a\u0628\u064a\u064a\u0636 \u0627\u0644\u0627\u0633\u0646\u0627\u0646<\/a><\/li>\n<li id=\"menu-item-946\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-946\"><a href=\"#\">\u062a\u0642\u0648\u064a\u0645 \u0627\u0644\u0623\u0633\u0646\u0627\u0646<\/a><\/li>\n<\/ul><\/div><\/div><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_bottom_spacing_normal\" data-bt-override-class=\"null\"><\/div><div class=\"bt_bb_column_inner_highlight\"><\/div><\/div><\/div><\/div><\/div><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_bottom_spacing_normal\" data-bt-override-class=\"null\"><\/div><div class=\"bt_bb_row_inner\"   data-bt-override-class=\"{}\"><div class=\"bt_bb_row_inner_holder\"  ><div  class=\"bt_bb_column_inner col-xxl-12 col-xl-12 bt_bb_align_left bt_bb_vertical_align_top bt_bb_padding_text_indent\" style=\"box-shadow: 0 0 0 8px #f2f2f2 inset;\" data-width=\"12\" data-bt-override-class=\"{}\"><div class=\"bt_bb_column_inner_content\"><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_bottom_spacing_normal\" data-bt-override-class=\"null\"><\/div><header class=\"bt_bb_headline bt_bb_color_scheme_3 bt_bb_dash_none bt_bb_size_normal bt_bb_align_inherit bt_bb_dash_type_none\" style=\"; --primary-color:#564c38; --secondary-color:#191919;\" data-bt-override-class=\"{}\"><h4 class=\"bt_bb_headline_tag\"><span class=\"bt_bb_headline_content\"><span>\u062a\u0648\u0627\u0635\u0644 \u0645\u0639\u0646\u0627<\/span><\/span><\/h4><\/header><div class=\"bt_bb_separator bt_bb_border_style_solid bt_bb_top_spacing_small bt_bb_bottom_spacing_small\" data-bt-override-class=\"null\"><\/div><div class=\"bt_bb_service bt_bb_color_scheme_7 bt_bb_style_borderless bt_bb_size_xlarge bt_bb_shape_circle bt_bb_target_self bt_bb_align_inherit\" style=\"; --primary-color:#6b5546; --secondary-color:#191919;\" data-bt-override-class=\"{}\"><span  data-ico-dentistry=\"&#xe92c;\" class=\"bt_bb_icon_holder\"><\/span><div class=\"bt_bb_service_content\"><div class=\"bt_bb_service_content_title\"><u>\u0627\u062a\u0635\u0644 \u0628\u0646\u0627 <\/u><\/div><div class=\"bt_bb_service_content_text\"><br \/><br \/>\n+962795615512<br \/><br \/>\n+962-6-4640558<\/div><\/div><\/div><div class=\"bt_bb_separator bt_bb_border_style_solid bt_bb_top_spacing_small bt_bb_bottom_spacing_small\" data-bt-override-class=\"null\"><\/div><div class=\"bt_bb_service bt_bb_color_scheme_7 bt_bb_style_borderless bt_bb_size_xlarge bt_bb_shape_circle bt_bb_target_self bt_bb_align_inherit\" style=\"; --primary-color:#6b5546; --secondary-color:#191919;\" data-bt-override-class=\"{}\"><span  data-ico-icon7stroke=\"&#xe63b;\" class=\"bt_bb_icon_holder\"><\/span><div class=\"bt_bb_service_content\"><div class=\"bt_bb_service_content_title\"><u>\u0627\u0644\u0627\u064a\u0645\u064a\u0644<\/u><\/div><div class=\"bt_bb_service_content_text\">info@dr-nimriclinic.com<\/div><\/div><\/div><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_bottom_spacing_normal\" data-bt-override-class=\"null\"><\/div><header class=\"bt_bb_headline bt_bb_color_scheme_3 bt_bb_dash_none bt_bb_size_normal bt_bb_align_inherit bt_bb_dash_type_none\" style=\"; --primary-color:#564c38; --secondary-color:#191919;\" data-bt-override-class=\"{}\"><h4 class=\"bt_bb_headline_tag\"><span class=\"bt_bb_headline_content\"><span>\u0627\u062d\u062c\u0632 \u0645\u0648\u0639\u062f\u0643<\/span><\/span><\/h4><\/header><div class=\"bt_bb_separator bt_bb_border_style_solid bt_bb_top_spacing_small bt_bb_bottom_spacing_small\" data-bt-override-class=\"null\"><\/div><div  class=\"bt_bb_text\" ><\/p>\n<p>\u0627\u062d\u062c\u0632 \u0632\u064a\u0627\u0631\u062a\u0643 \u0625\u0644\u0649 \u0639\u064a\u0627\u062f\u0629 \u062f. \u0648\u0633\u0627\u0645 \u0627\u0644\u0646\u0645\u0631\u064a\u060c \u0641\u0642\u0637 \u0642\u0645 \u0628\u0645\u0644\u0621 \u0627\u0644\u0646\u0645\u0648\u0630\u062c \u0623\u062f\u0646\u0627\u0647 \u0648\u0633\u0646\u0642\u0648\u0645 \u0628\u0627\u0644\u062a\u0648\u0627\u0635\u0644 \u0645\u0639\u0643 \u0628\u062e\u0635\u0648\u0635 \u0627\u0644\u0639\u0644\u0627\u062c \u0627\u0644\u0630\u064a \u062a\u062d\u062a\u0627\u062c\u0647.<\/p>\n<p>\n<\/div><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_bottom_spacing_small\" data-bt-override-class=\"null\"><\/div><div class=\"bt_bb_contact_form_7\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f934-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"934\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/ar\/wp-json\/wp\/v2\/pages\/1581#wpcf7-f934-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/ar\/wp-json\/wp\/v2\/pages\/1581#wpcf7-f934-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"934\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f934-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"bt_bb_cf7_form\">\n\t<div class=\"bt_bb_cf7_row\">\n\t\t<div class=\"bt_bb_cf7_element\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Enter your Name *\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"bt_bb_cf7_row\">\n\t\t<div class=\"bt_bb_cf7_element\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Enter your Email Address *\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"bt_bb_cf7_row\">\n\t\t<div class=\"bt_bb_cf7_element\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"menu-974\"><select class=\"wpcf7-form-control wpcf7-select\" aria-invalid=\"false\" name=\"menu-974\"><option value=\"Please select your dentist\">Please select your dentist<\/option><option value=\"Allen Fischer\">Allen Fischer<\/option><option value=\"Alex Terrel\">Alex Terrel<\/option><option value=\"Mich\u00e9l Anderson\">Mich\u00e9l Anderson<\/option><option value=\"Edwin Southgate\">Edwin Southgate<\/option><option value=\"Carlie Addison\">Carlie Addison<\/option><\/select><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"bt_bb_cf7_row\">\n\t\t<div class=\"bt_bb_cf7_element\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"appointment-date\"><input class=\"wpcf7-form-control wpcf7-date wpcf7-validates-as-required wpcf7-validates-as-date\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Appointment date *\" value=\"\" type=\"date\" name=\"appointment-date\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"bt_bb_cf7_row\">\n\t\t<div class=\"bt_bb_cf7_element\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"9\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Additional Message\" name=\"your-message\"><\/textarea><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"bt_bb_cf7_row\">\n\t\t<div class=\"bt_bb_cf7_button bt_bb_cf7_button_larger bt_bb_cf7_element\">\n\t\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"\u0627\u062d\u062c\u0632 \u0645\u0648\u0639\u062f\u0643\" \/>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"ar\"\/><\/form>\n<\/div>\n<\/div><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_bottom_spacing_normal\" data-bt-override-class=\"null\"><\/div><div class=\"bt_bb_column_inner_highlight\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><!-- cell_inner --><\/div><!-- cell --><\/div><!-- port --><\/section><section id=\"bt_bb_section6a57f99fa1b7d\" class=\"bt_bb_section bt_bb_layout_boxed_1200 bt_bb_vertical_align_top bt_bb_top_spacing_large bt_bb_bottom_spacing_large\"  data-bt-override-class=\"null\"><div class=\"bt_bb_background_image_holder_wrapper\"><div class=\"bt_bb_background_image_holder btLazyLoadBackground\"  data-background_image_src=\"https:\/\/dr-nimriclinic.com\/wp-content\/uploads\/2020\/03\/background-doctor.jpg\" data-parallax-zoom-start=\"1\" data-parallax-zoom-end=\"1\" data-parallax-blur-start=\"0\" data-parallax-blur-end=\"0\" data-parallax-opacity-start=\"1\" data-parallax-opacity-end=\"1\" style=\" background-image: url(&#039;https:\/\/dr-nimriclinic.com\/wp-content\/plugins\/bold-page-builder\/img\/blank.gif&#039;);\"><\/div><\/div><div class=\"bt_bb_port\"><div class=\"bt_bb_cell\"><div class=\"bt_bb_cell_inner\"><div class=\"bt_bb_row\"  data-bt-override-class=\"{}\"><div class=\"bt_bb_row_holder\" ><div  class=\"bt_bb_column col-xxl-8 col-xl-8 bt_bb_vertical_align_top bt_bb_align_left bt_bb_padding_normal bt_bb_animation_fade_in animate\"  data-width=\"8\" data-bt-override-class=\"{}\"><div class=\"bt_bb_column_content\"><header class=\"bt_bb_headline bt_bb_font_weight_bolder bt_bb_color_scheme_17 bt_bb_dash_none bt_bb_size_extralarge bt_bb_align_inherit bt_bb_dash_type_none\" style=\"; --primary-color:#6b5546; --secondary-color:#564c38;\" data-bt-override-class=\"{}\"><h2 class=\"bt_bb_headline_tag translation-block\"><span class=\"bt_bb_headline_content\"><span><small>\u0645\u0644\u062a\u0632\u0645\u0648\u0646 \u0628\u0640<\/small><br>\u0627\u0644\u062a\u0645\u064a\u0651\u0632<\/span><\/span><\/h2><\/header><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_bottom_spacing_normal\" data-bt-override-class=\"null\"><\/div><div class=\"bt_bb_button bt_bb_color_scheme_11 bt_bb_icon_position_right bt_bb_style_filled bt_bb_size_medium bt_bb_width_inline bt_bb_shape_inherit bt_bb_target_self bt_bb_align_inherit bt_bb_hidden_md bt_bb_hidden_lg\" style=\"; --primary-color:#ffffff; --secondary-color:#6b5546;\" data-bt-override-class=\"{}\"><a href=\"#\" target=\"_self\" class=\"bt_bb_link\" title=\"\u062c\u0645\u064a\u0639 \u0627\u0644\u062e\u062f\u0645\u0627\u062a\"><span class=\"bt_bb_button_text\" >\u062c\u0645\u064a\u0639 \u0627\u0644\u062e\u062f\u0645\u0627\u062a<\/span><span  data-ico-fontawesome=\"&#xf105;\" class=\"bt_bb_icon_holder\"><\/span><\/a><\/div><\/div><\/div><div  class=\"bt_bb_column col-xxl-4 col-xl-4 bt_bb_vertical_align_bottom bt_bb_align_right bt_bb_padding_normal bt_bb_animation_fade_in animate\"  data-width=\"4\" data-bt-override-class=\"{}\"><div class=\"bt_bb_column_content\"><div class=\"bt_bb_button bt_bb_color_scheme_11 bt_bb_icon_position_right bt_bb_style_filled bt_bb_size_medium bt_bb_width_inline bt_bb_shape_inherit bt_bb_target_self bt_bb_align_inherit bt_bb_hidden_xs bt_bb_hidden_ms bt_bb_hidden_sm\" style=\"; --primary-color:#ffffff; --secondary-color:#6b5546;\" data-bt-override-class=\"{}\"><a href=\"#\" target=\"_self\" class=\"bt_bb_link\" title=\"\u062c\u0645\u064a\u0639 \u0627\u0644\u062e\u062f\u0645\u0627\u062a\"><span class=\"bt_bb_button_text\" >\u062c\u0645\u064a\u0639 \u0627\u0644\u062e\u062f\u0645\u0627\u062a<\/span><span  data-ico-fontawesome=\"&#xf105;\" class=\"bt_bb_icon_holder\"><\/span><\/a><\/div><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_bottom_spacing_normal\" data-bt-override-class=\"null\"><\/div><\/div><\/div><\/div><\/div><div class=\"bt_bb_row  bt_bb_column_gap_10\" style=\"; --column-gap:10px;\" data-bt-override-class=\"{}\"><div class=\"bt_bb_row_holder\" style=\"margin-bottom: -40px;\"><div  class=\"bt_bb_column col-xxl-3 col-xl-3 bt_bb_vertical_align_top bt_bb_align_left bt_bb_highlight bt_bb_padding_text_indent bt_bb_animation_fade_in move_up animate\" style=\"margin-bottom: 20px;\" data-width=\"3\" data-bt-override-class=\"{}\"><div class=\"bt_bb_column_content\" style=\"background-color:rgba(255, 255, 255, 1);\"><div class=\"bt_bb_image bt_bb_shape_square bt_bb_target_self bt_bb_align_inherit bt_bb_hover_style_simple bt_bb_content_display_show-on-hover bt_bb_content_align_middle bt_bb_content_exists\" data-bt-override-class=\"{}\"><a href=\"#\"  target=\"_self\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/dr-nimriclinic.com\/wp-content\/uploads\/2020\/01\/home-services.jpg\" class=\"attachment-full size-full\" alt=\"https:\/\/dr-nimriclinic.com\/wp-content\/uploads\/2020\/01\/home-services.jpg\" data-full_image_src=\"https:\/\/dr-nimriclinic.com\/wp-content\/uploads\/2020\/01\/home-services.jpg\" srcset=\"https:\/\/dr-nimriclinic.com\/wp-content\/uploads\/2020\/01\/home-services.jpg 1200w, https:\/\/dr-nimriclinic.com\/wp-content\/uploads\/2020\/01\/home-services-640x427.jpg 640w, https:\/\/dr-nimriclinic.com\/wp-content\/uploads\/2020\/01\/home-services-768x512.jpg 768w, https:\/\/dr-nimriclinic.com\/wp-content\/uploads\/2020\/01\/home-services-320x213.jpg 320w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a><div class=\"bt_bb_image_content\"  style=\"background-color: rgba(255, 255, 255, 0.3);\"><div class=\"bt_bb_image_content_flex\"><div class=\"bt_bb_image_content_inner\"><div class=\"bt_bb_separator bt_bb_border_style_none\" data-bt-override-class=\"null\"><\/div><\/div><\/div><\/div><\/div><div class=\"bt_bb_icon bt_bb_color_scheme_6 bt_bb_style_filled bt_bb_size_large bt_bb_shape_square bt_bb_target_self bt_bb_text_empty bt_bb_align_inherit bt_bb_vertical_position_half_above\" style=\"box-shadow: 0 2px 10px rgba(0,0,0,.2); padding: 0;; --primary-color:#ffffff; --secondary-color:#564c38;\" data-bt-override-class=\"{}\"><span  data-ico-dentalcare=\"&#xe903;\" class=\"bt_bb_icon_holder\"><\/span><\/div><div class=\"bt_bb_separator bt_bb_border_style_none\" data-bt-override-class=\"null\"><\/div><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_top_spacing_extra_small bt_bb_bottom_spacing_small\" data-bt-override-class=\"null\"><\/div><header class=\"bt_bb_headline bt_bb_dash_none bt_bb_size_normal bt_bb_align_inherit bt_bb_dash_type_none\" data-bt-override-class=\"{}\"><h4 class=\"bt_bb_headline_tag\"><span class=\"bt_bb_headline_content\"><span>\u062e\u062f\u0645\u0627\u062a \u0627\u0644\u0623\u0633\u0646\u0627\u0646<\/span><\/span><\/h4><\/header><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_bottom_spacing_extra_small\" data-bt-override-class=\"null\"><\/div><div  class=\"bt_bb_text\" ><\/p>\n<p>\u062e\u062f\u0645\u0627\u062a \u0637\u0628 \u0623\u0633\u0646\u0627\u0646 \u0634\u0627\u0645\u0644\u0629 \u0645\u0635\u0645\u0645\u0629 \u0644\u0644\u062d\u0641\u0627\u0638 \u0639\u0644\u0649 \u0627\u0628\u062a\u0633\u0627\u0645\u062a\u0643 \u0635\u062d\u064a\u0629 \u0648\u0645\u0634\u0631\u0642\u0629 \u0648\u0648\u0627\u062b\u0642\u0629. \u0645\u0646 \u0627\u0644\u0631\u0639\u0627\u064a\u0629 \u0627\u0644\u0648\u0642\u0627\u0626\u064a\u0629 \u0625\u0644\u0649 \u0627\u0644\u0639\u0644\u0627\u062c\u0627\u062a \u0627\u0644\u0645\u062a\u0642\u062f\u0645\u0629\u060c \u0646\u0642\u062f\u0645 \u062d\u0644\u0648\u0644\u064b\u0627 \u0645\u062e\u0635\u0635\u0629 \u0644\u0643\u0644 \u0645\u0631\u064a\u0636.<\/p>\n<p>\n<\/div><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_top_spacing_extra_small bt_bb_bottom_spacing_small\" data-bt-override-class=\"null\"><\/div><div class=\"bt_bb_column_highlight\"><\/div><\/div><\/div><div  class=\"bt_bb_column col-xxl-3 col-xl-3 bt_bb_vertical_align_top bt_bb_align_left bt_bb_highlight bt_bb_padding_text_indent bt_bb_animation_fade_in move_up animate\" style=\"margin-bottom: 20px;\" data-width=\"3\" data-bt-override-class=\"{}\"><div class=\"bt_bb_column_content\" style=\"background-color:rgba(255, 255, 255, 1);\"><div class=\"bt_bb_image bt_bb_shape_square bt_bb_target_self bt_bb_align_inherit bt_bb_hover_style_simple bt_bb_content_display_show-on-hover bt_bb_content_align_middle bt_bb_content_exists\" data-bt-override-class=\"{}\"><a href=\"#\"  target=\"_self\"><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/dr-nimriclinic.com\/wp-content\/uploads\/2020\/01\/home-services-2.jpg\" class=\"attachment-full size-full\" alt=\"https:\/\/dr-nimriclinic.com\/wp-content\/uploads\/2020\/01\/home-services-2.jpg\" data-full_image_src=\"https:\/\/dr-nimriclinic.com\/wp-content\/uploads\/2020\/01\/home-services-2.jpg\" srcset=\"https:\/\/dr-nimriclinic.com\/wp-content\/uploads\/2020\/01\/home-services-2.jpg 1200w, https:\/\/dr-nimriclinic.com\/wp-content\/uploads\/2020\/01\/home-services-2-640x427.jpg 640w, https:\/\/dr-nimriclinic.com\/wp-content\/uploads\/2020\/01\/home-services-2-768x512.jpg 768w, https:\/\/dr-nimriclinic.com\/wp-content\/uploads\/2020\/01\/home-services-2-320x213.jpg 320w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a><div class=\"bt_bb_image_content\"  style=\"background-color: rgba(255, 255, 255, 0.3);\"><div class=\"bt_bb_image_content_flex\"><div class=\"bt_bb_image_content_inner\"><div class=\"bt_bb_separator bt_bb_border_style_none\" data-bt-override-class=\"null\"><\/div><\/div><\/div><\/div><\/div><div class=\"bt_bb_icon bt_bb_color_scheme_6 bt_bb_style_filled bt_bb_size_large bt_bb_shape_square bt_bb_target_self bt_bb_text_empty bt_bb_align_inherit bt_bb_vertical_position_half_above\" style=\"box-shadow: 0 2px 10px rgba(0,0,0,.2); padding: 0;; --primary-color:#ffffff; --secondary-color:#564c38;\" data-bt-override-class=\"{}\"><span  data-ico-dentalcare=\"&#xe929;\" class=\"bt_bb_icon_holder\"><\/span><\/div><div class=\"bt_bb_separator bt_bb_border_style_none\" data-bt-override-class=\"null\"><\/div><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_top_spacing_extra_small bt_bb_bottom_spacing_small\" data-bt-override-class=\"null\"><\/div><header class=\"bt_bb_headline bt_bb_dash_none bt_bb_size_normal bt_bb_align_inherit bt_bb_dash_type_none\" data-bt-override-class=\"{}\"><h4 class=\"bt_bb_headline_tag\"><span class=\"bt_bb_headline_content\"><span>\u0632\u0631\u0627\u0639\u0629 \u0627\u0644\u0623\u0633\u0646\u0627\u0646<\/span><\/span><\/h4><\/header><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_bottom_spacing_extra_small\" data-bt-override-class=\"null\"><\/div><div  class=\"bt_bb_text\" ><\/p>\n<p>\u0627\u0633\u062a\u0639\u062f \u0627\u0628\u062a\u0633\u0627\u0645\u062a\u0643 \u0645\u0639 \u0632\u0631\u0627\u0639\u0629 \u0627\u0644\u0623\u0633\u0646\u0627\u0646 \u0627\u0644\u0645\u062a\u0642\u062f\u0645\u0629 \u0627\u0644\u062a\u064a \u062a\u0628\u062f\u0648 \u0648\u062a\u064f\u062d\u0633\u0651 \u0648\u062a\u0639\u0645\u0644 \u0645\u062b\u0644 \u0627\u0644\u0623\u0633\u0646\u0627\u0646 \u0627\u0644\u0637\u0628\u064a\u0639\u064a\u0629. \u062d\u0644 \u0637\u0648\u064a\u0644 \u0627\u0644\u0623\u0645\u062f \u0645\u0635\u0645\u0645 \u0644\u0627\u0633\u062a\u0639\u0627\u062f\u0629 \u0627\u0644\u062b\u0642\u0629 \u0648\u0627\u0644\u0631\u0627\u062d\u0629 \u0648\u0627\u0644\u0648\u0638\u064a\u0641\u0629 \u0627\u0644\u0643\u0627\u0645\u0644\u0629 \u0644\u0644\u0641\u0645.<\/p>\n<p>\n<\/div><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_top_spacing_extra_small bt_bb_bottom_spacing_small\" data-bt-override-class=\"null\"><\/div><div class=\"bt_bb_column_highlight\"><\/div><\/div><\/div><div  class=\"bt_bb_column col-xxl-3 col-xl-3 bt_bb_vertical_align_top bt_bb_align_left bt_bb_highlight bt_bb_padding_text_indent bt_bb_animation_fade_in move_up animate\" style=\"margin-bottom: 20px;\" data-width=\"3\" data-bt-override-class=\"{}\"><div class=\"bt_bb_column_content\" style=\"background-color:rgba(255, 255, 255, 1);\"><div class=\"bt_bb_image bt_bb_shape_square bt_bb_target_self bt_bb_align_inherit bt_bb_hover_style_simple bt_bb_content_display_show-on-hover bt_bb_content_align_middle bt_bb_content_exists\" data-bt-override-class=\"{}\"><a href=\"#\"  target=\"_self\"><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/dr-nimriclinic.com\/wp-content\/uploads\/2020\/01\/home-services-3.jpg\" class=\"attachment-full size-full\" alt=\"https:\/\/dr-nimriclinic.com\/wp-content\/uploads\/2020\/01\/home-services-3.jpg\" data-full_image_src=\"https:\/\/dr-nimriclinic.com\/wp-content\/uploads\/2020\/01\/home-services-3.jpg\" srcset=\"https:\/\/dr-nimriclinic.com\/wp-content\/uploads\/2020\/01\/home-services-3.jpg 1200w, https:\/\/dr-nimriclinic.com\/wp-content\/uploads\/2020\/01\/home-services-3-640x427.jpg 640w, https:\/\/dr-nimriclinic.com\/wp-content\/uploads\/2020\/01\/home-services-3-768x512.jpg 768w, https:\/\/dr-nimriclinic.com\/wp-content\/uploads\/2020\/01\/home-services-3-320x213.jpg 320w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a><div class=\"bt_bb_image_content\"  style=\"background-color: rgba(255, 255, 255, 0.3);\"><div class=\"bt_bb_image_content_flex\"><div class=\"bt_bb_image_content_inner\"><div class=\"bt_bb_separator bt_bb_border_style_none\" data-bt-override-class=\"null\"><\/div><\/div><\/div><\/div><\/div><div class=\"bt_bb_icon bt_bb_color_scheme_6 bt_bb_style_filled bt_bb_size_large bt_bb_shape_square bt_bb_target_self bt_bb_text_empty bt_bb_align_inherit bt_bb_vertical_position_half_above\" style=\"box-shadow: 0 2px 10px rgba(0,0,0,.2); padding: 0;; --primary-color:#ffffff; --secondary-color:#564c38;\" data-bt-override-class=\"{}\"><span  data-ico-dentalcare=\"&#xe92a;\" class=\"bt_bb_icon_holder\"><\/span><\/div><div class=\"bt_bb_separator bt_bb_border_style_none\" data-bt-override-class=\"null\"><\/div><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_top_spacing_extra_small bt_bb_bottom_spacing_small\" data-bt-override-class=\"null\"><\/div><header class=\"bt_bb_headline bt_bb_dash_none bt_bb_size_normal bt_bb_align_inherit bt_bb_dash_type_none\" data-bt-override-class=\"{}\"><h4 class=\"bt_bb_headline_tag\"><span class=\"bt_bb_headline_content\"><span>\u0631\u0639\u0627\u064a\u0629 \u062c\u0631\u0627\u062d\u064a\u0629<\/span><\/span><\/h4><\/header><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_bottom_spacing_extra_small\" data-bt-override-class=\"null\"><\/div><div  class=\"bt_bb_text\" ><\/p>\n<p>\u0627\u062e\u062a\u0628\u0631 \u0631\u0639\u0627\u064a\u0629 \u062c\u0631\u0627\u062d\u064a\u0629 \u0622\u0645\u0646\u0629 \u0648\u0645\u062a\u0642\u062f\u0645\u0629 \u062a\u0647\u062f\u0641 \u0625\u0644\u0649 \u0627\u0633\u062a\u0639\u0627\u062f\u0629 \u0635\u062d\u062a\u0643\u060c \u0648\u062a\u062e\u0641\u064a\u0641 \u0627\u0644\u0623\u0644\u0645\u060c \u0648\u062a\u062d\u0642\u064a\u0642 \u0646\u062a\u0627\u0626\u062c \u062f\u0642\u064a\u0642\u0629 \u0628\u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0623\u062d\u062f\u062b \u0627\u0644\u062a\u0642\u0646\u064a\u0627\u062a \u0648\u0628\u0623\u064a\u062f\u064d \u062e\u0628\u064a\u0631\u0629.<\/p>\n<p>\n<\/div><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_top_spacing_extra_small bt_bb_bottom_spacing_small\" data-bt-override-class=\"null\"><\/div><div class=\"bt_bb_column_highlight\"><\/div><\/div><\/div><div  class=\"bt_bb_column col-xxl-3 col-xl-3 bt_bb_vertical_align_top bt_bb_align_left bt_bb_highlight bt_bb_padding_text_indent bt_bb_animation_fade_in move_up animate\" style=\"margin-bottom: 20px;\" data-width=\"3\" data-bt-override-class=\"{}\"><div class=\"bt_bb_column_content\" style=\"background-color:rgba(255, 255, 255, 1);\"><div class=\"bt_bb_image bt_bb_shape_square bt_bb_target_self bt_bb_align_inherit bt_bb_hover_style_simple bt_bb_content_display_show-on-hover bt_bb_content_align_middle bt_bb_content_exists\" data-bt-override-class=\"{}\"><a href=\"#\"  target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/dr-nimriclinic.com\/wp-content\/uploads\/2020\/01\/home-services-4.jpg\" class=\"attachment-full size-full\" alt=\"https:\/\/dr-nimriclinic.com\/wp-content\/uploads\/2020\/01\/home-services-4.jpg\" data-full_image_src=\"https:\/\/dr-nimriclinic.com\/wp-content\/uploads\/2020\/01\/home-services-4.jpg\" srcset=\"https:\/\/dr-nimriclinic.com\/wp-content\/uploads\/2020\/01\/home-services-4.jpg 1200w, https:\/\/dr-nimriclinic.com\/wp-content\/uploads\/2020\/01\/home-services-4-640x427.jpg 640w, https:\/\/dr-nimriclinic.com\/wp-content\/uploads\/2020\/01\/home-services-4-768x512.jpg 768w, https:\/\/dr-nimriclinic.com\/wp-content\/uploads\/2020\/01\/home-services-4-320x213.jpg 320w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a><div class=\"bt_bb_image_content\"  style=\"background-color: rgba(255, 255, 255, 0.3);\"><div class=\"bt_bb_image_content_flex\"><div class=\"bt_bb_image_content_inner\"><div class=\"bt_bb_separator bt_bb_border_style_none\" data-bt-override-class=\"null\"><\/div><\/div><\/div><\/div><\/div><div class=\"bt_bb_icon bt_bb_color_scheme_6 bt_bb_style_filled bt_bb_size_large bt_bb_shape_square bt_bb_target_self bt_bb_text_empty bt_bb_align_inherit bt_bb_vertical_position_half_above\" style=\"box-shadow: 0 2px 10px rgba(0,0,0,.2); padding: 0;; --primary-color:#ffffff; --secondary-color:#564c38;\" data-bt-override-class=\"{}\"><span  data-ico-dentalcare=\"&#xe901;\" class=\"bt_bb_icon_holder\"><\/span><\/div><div class=\"bt_bb_separator bt_bb_border_style_none\" data-bt-override-class=\"null\"><\/div><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_top_spacing_extra_small bt_bb_bottom_spacing_small\" data-bt-override-class=\"null\"><\/div><header class=\"bt_bb_headline bt_bb_dash_none bt_bb_size_normal bt_bb_align_inherit bt_bb_dash_type_none\" data-bt-override-class=\"{}\"><h4 class=\"bt_bb_headline_tag\"><span class=\"bt_bb_headline_content\"><span>\u062a\u0628\u064a\u064a\u0636 \u0627\u0644\u0623\u0633\u0646\u0627\u0646<\/span><\/span><\/h4><\/header><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_bottom_spacing_extra_small\" data-bt-override-class=\"null\"><\/div><div  class=\"bt_bb_text\" ><\/p>\n<p>\u0623\u0638\u0647\u0631 \u0627\u0628\u062a\u0633\u0627\u0645\u0629 \u0623\u0643\u062b\u0631 \u0625\u0634\u0631\u0627\u0642\u064b\u0627 \u0648\u0628\u064a\u0627\u0636\u064b\u0627 \u0645\u0639 \u0639\u0644\u0627\u062c\u0627\u062a \u062a\u0628\u064a\u064a\u0636 \u0627\u0644\u0623\u0633\u0646\u0627\u0646 \u0627\u0644\u0627\u062d\u062a\u0631\u0627\u0641\u064a\u0629 \u0644\u062f\u064a\u0646\u0627\u060c \u0627\u0644\u0645\u0635\u0645\u0645\u0629 \u0644\u0625\u0632\u0627\u0644\u0629 \u0627\u0644\u062a\u0635\u0628\u063a\u0627\u062a \u0628\u0623\u0645\u0627\u0646 \u0648\u062a\u0639\u0632\u064a\u0632 \u062c\u0645\u0627\u0644 \u0627\u0628\u062a\u0633\u0627\u0645\u062a\u0643 \u0627\u0644\u0637\u0628\u064a\u0639\u064a\u0629 \u0641\u064a \u062c\u0644\u0633\u0629 \u0648\u0627\u062d\u062f\u0629 \u0641\u0642\u0637.<\/p>\n<p>\n<\/div><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_top_spacing_extra_small bt_bb_bottom_spacing_small\" data-bt-override-class=\"null\"><\/div><div class=\"bt_bb_column_highlight\"><\/div><\/div><\/div><\/div><\/div><\/div><!-- cell_inner --><\/div><!-- cell --><\/div><!-- port --><\/section><\/p>","protected":false},"excerpt":{"rendered":"<p>Credibly reintermediate backend ideas for cross-platform models. Continually reintermediate integrated processes through technically sound intellectual capital. Holistically foster superior methodologies without market-driven best practices.<\/p>","protected":false},"author":1,"featured_media":0,"parent":147,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1581","page","type-page","status-publish","hentry"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"alaa.alasmar88@yahoo.com","author_link":"https:\/\/dr-nimriclinic.com\/ar\/author\/alaa-alasmar88yahoo-com\/"},"rttpg_comment":0,"rttpg_category":null,"rttpg_excerpt":"Credibly reintermediate backend ideas for cross-platform models. Continually reintermediate integrated processes through technically sound intellectual capital. Holistically foster superior methodologies without market-driven best practices.","_links":{"self":[{"href":"https:\/\/dr-nimriclinic.com\/ar\/wp-json\/wp\/v2\/pages\/1581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dr-nimriclinic.com\/ar\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dr-nimriclinic.com\/ar\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dr-nimriclinic.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dr-nimriclinic.com\/ar\/wp-json\/wp\/v2\/comments?post=1581"}],"version-history":[{"count":7,"href":"https:\/\/dr-nimriclinic.com\/ar\/wp-json\/wp\/v2\/pages\/1581\/revisions"}],"predecessor-version":[{"id":2528,"href":"https:\/\/dr-nimriclinic.com\/ar\/wp-json\/wp\/v2\/pages\/1581\/revisions\/2528"}],"up":[{"embeddable":true,"href":"https:\/\/dr-nimriclinic.com\/ar\/wp-json\/wp\/v2\/pages\/147"}],"wp:attachment":[{"href":"https:\/\/dr-nimriclinic.com\/ar\/wp-json\/wp\/v2\/media?parent=1581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}